{"id":8875,"date":"2022-05-16T14:19:41","date_gmt":"2022-05-16T13:19:41","guid":{"rendered":"https:\/\/riberalves.pt\/?post_type=receitas&#038;p=8875"},"modified":"2024-03-08T15:21:28","modified_gmt":"2024-03-08T15:21:28","slug":"salade-cesar-a-la-morue","status":"publish","type":"receitas","link":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/","title":{"rendered":"Salade C\u00e9sar \u00e0 la morue"},"content":{"rendered":"\n<p>Un ingr\u00e9dient sp\u00e9cial pour une recette fra\u00eeche et savoureuse : Salade C\u00e9sar \u00e0 la <a href=\"https:\/\/riberalves.pt\/fr\/gamme-produits\/consommation-domestique\/\" target=\"_blank\" rel=\"noreferrer noopener\">morue<\/a> ! D\u00e9couvrez-la.<\/p>\n\n\n\n<p>D\u00e9congelez les tranches de morue, passez-les sous un filet d&rsquo;eau froide et s\u00e9chez-les avec du papier absorbant.<\/p>\n\n\n\n<p>Chauffez l&rsquo;huile d&rsquo;olive, faites dorer les gousses d&rsquo;ail \u00e9cras\u00e9es puis retirez les gousses d&rsquo;ail. Disposez les tranches de morue dans l&rsquo;huile d&rsquo;olive aromatis\u00e9 et faites revenir 3 \u00e0 5 minutes de chaque c\u00f4t\u00e9. Ensuite, retirez la peau et les ar\u00eates et effilez en copeaux.<\/p>\n\n\n\n<p>Effeuillez la laitue iceberg et faites de fins copeaux de parmesan avec un couteau ou un \u00e9plucheur de carottes.<\/p>\n\n\n\n<p>R\u00e9partissez dans chaque bol la laitue, puis les copeaux de morue, saupoudrez de parmesan et de cro\u00fbtons, assaisonnez avec la vinaigrette C\u00e9sar et le poivre noir \u00e0 votre go\u00fbt.<\/p>\n\n\n\n<p>La salade C\u00e9sar \u00e0 la morue est pr\u00eate !<\/p>\n\n\n\n<p style=\"font-size:30px\"><strong><u><a href=\"https:\/\/www.instagram.com\/bacalhau_riberalves\/\" target=\"_blank\" rel=\"noreferrer noopener\">PR\u00caTE \u00c0 \u00caTRE SAVOUR\u00c9E !<\/a><\/u><\/strong><strong><\/strong><\/p>\n","protected":false},"featured_media":7283,"template":"","categories":[39,252,41,57],"colecoes":[326,329,341,338,344],"tipos-bacalhau":[245],"class_list":["post-8875","receitas","type-receitas","status-publish","has-post-thumbnail","hentry","category-entrees-et-aperitifs","category-originais-fr","category-plats-froids","category-printemps-ete","colecoes-occasions-speciales","colecoes-original-et-innovant","colecoes-plats-familiaux","colecoes-printemps-ete","colecoes-salades","tipos-bacalhau-tranche-de-morue"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salade C\u00e9sar \u00e0 la morue - Riberalves<\/title>\n<meta name=\"description\" content=\"Un ingr\u00e9dient sp\u00e9cial pour une recette fra\u00eeche et savoureuse: Salade C\u00e9sar \u00e0 la morue! D\u00e9couvrez-la. Pr\u00eate \u00e0 cuisiner, pr\u00eate \u00e0 \u00eatre savour\u00e9e!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salade C\u00e9sar \u00e0 la morue - Riberalves\" \/>\n<meta property=\"og:description\" content=\"Un ingr\u00e9dient sp\u00e9cial pour une recette fra\u00eeche et savoureuse: Salade C\u00e9sar \u00e0 la morue! D\u00e9couvrez-la. Pr\u00eate \u00e0 cuisiner, pr\u00eate \u00e0 \u00eatre savour\u00e9e!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/\" \/>\n<meta property=\"og:site_name\" content=\"Riberalves\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T15:21:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/riberalves.pt\/wp-content\/uploads\/2021\/08\/SaladaCesarBac_1200x1460_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/riberalves.pt\\\/fr\\\/recettes\\\/salade-cesar-a-la-morue\\\/\",\"url\":\"https:\\\/\\\/riberalves.pt\\\/fr\\\/recettes\\\/salade-cesar-a-la-morue\\\/\",\"name\":\"Salade C\u00e9sar \u00e0 la morue - Riberalves\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/riberalves.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/riberalves.pt\\\/fr\\\/recettes\\\/salade-cesar-a-la-morue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/riberalves.pt\\\/fr\\\/recettes\\\/salade-cesar-a-la-morue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/riberalves.pt\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/SaladaCesarBac_1200x1460_02.jpg\",\"datePublished\":\"2022-05-16T13:19:41+00:00\",\"dateModified\":\"2024-03-08T15:21:28+00:00\",\"description\":\"Un ingr\u00e9dient sp\u00e9cial pour une recette fra\u00eeche et savoureuse: Salade C\u00e9sar \u00e0 la morue! D\u00e9couvrez-la. Pr\u00eate \u00e0 cuisiner, pr\u00eate \u00e0 \u00eatre savour\u00e9e!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/riberalves.pt\\\/fr\\\/recettes\\\/salade-cesar-a-la-morue\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/riberalves.pt\\\/fr\\\/recettes\\\/salade-cesar-a-la-morue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/riberalves.pt\\\/fr\\\/recettes\\\/salade-cesar-a-la-morue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/riberalves.pt\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/SaladaCesarBac_1200x1460_02.jpg\",\"contentUrl\":\"https:\\\/\\\/riberalves.pt\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/SaladaCesarBac_1200x1460_02.jpg\",\"width\":1200,\"height\":1460,\"caption\":\"Salade C\u00e9sar \u00e0 la morue! - Pr\u00eate \u00e0 cuisiner, pr\u00eate \u00e0 \u00eatre savour\u00e9e!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/riberalves.pt\\\/fr\\\/recettes\\\/salade-cesar-a-la-morue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/riberalves.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Receitas\",\"item\":\"https:\\\/\\\/riberalves.pt\\\/receitas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salade C\u00e9sar \u00e0 la morue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/riberalves.pt\\\/#website\",\"url\":\"https:\\\/\\\/riberalves.pt\\\/\",\"name\":\"Riberalves\",\"description\":\"Les meilleures recettes de morue en un seul endroit! Notre processus de longue matuaration dans le sel garantit la saveur unique, la texture douce et les tranches succulentes de notre poisson pr\u00e9f\u00e9r\u00e9, pr\u00eat \u00e0 cuisiner!\",\"alternateName\":\"Riberalves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/riberalves.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salade C\u00e9sar \u00e0 la morue - Riberalves","description":"Un ingr\u00e9dient sp\u00e9cial pour une recette fra\u00eeche et savoureuse: Salade C\u00e9sar \u00e0 la morue! D\u00e9couvrez-la. Pr\u00eate \u00e0 cuisiner, pr\u00eate \u00e0 \u00eatre savour\u00e9e!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/","og_locale":"fr_FR","og_type":"article","og_title":"Salade C\u00e9sar \u00e0 la morue - Riberalves","og_description":"Un ingr\u00e9dient sp\u00e9cial pour une recette fra\u00eeche et savoureuse: Salade C\u00e9sar \u00e0 la morue! D\u00e9couvrez-la. Pr\u00eate \u00e0 cuisiner, pr\u00eate \u00e0 \u00eatre savour\u00e9e!","og_url":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/","og_site_name":"Riberalves","article_modified_time":"2024-03-08T15:21:28+00:00","og_image":[{"width":1200,"height":1460,"url":"https:\/\/riberalves.pt\/wp-content\/uploads\/2021\/08\/SaladaCesarBac_1200x1460_02.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/","url":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/","name":"Salade C\u00e9sar \u00e0 la morue - Riberalves","isPartOf":{"@id":"https:\/\/riberalves.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/#primaryimage"},"image":{"@id":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/#primaryimage"},"thumbnailUrl":"https:\/\/riberalves.pt\/wp-content\/uploads\/2021\/08\/SaladaCesarBac_1200x1460_02.jpg","datePublished":"2022-05-16T13:19:41+00:00","dateModified":"2024-03-08T15:21:28+00:00","description":"Un ingr\u00e9dient sp\u00e9cial pour une recette fra\u00eeche et savoureuse: Salade C\u00e9sar \u00e0 la morue! D\u00e9couvrez-la. Pr\u00eate \u00e0 cuisiner, pr\u00eate \u00e0 \u00eatre savour\u00e9e!","breadcrumb":{"@id":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/#primaryimage","url":"https:\/\/riberalves.pt\/wp-content\/uploads\/2021\/08\/SaladaCesarBac_1200x1460_02.jpg","contentUrl":"https:\/\/riberalves.pt\/wp-content\/uploads\/2021\/08\/SaladaCesarBac_1200x1460_02.jpg","width":1200,"height":1460,"caption":"Salade C\u00e9sar \u00e0 la morue! - Pr\u00eate \u00e0 cuisiner, pr\u00eate \u00e0 \u00eatre savour\u00e9e!"},{"@type":"BreadcrumbList","@id":"https:\/\/riberalves.pt\/fr\/recettes\/salade-cesar-a-la-morue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/riberalves.pt\/"},{"@type":"ListItem","position":2,"name":"Receitas","item":"https:\/\/riberalves.pt\/receitas\/"},{"@type":"ListItem","position":3,"name":"Salade C\u00e9sar \u00e0 la morue"}]},{"@type":"WebSite","@id":"https:\/\/riberalves.pt\/#website","url":"https:\/\/riberalves.pt\/","name":"Riberalves","description":"Les meilleures recettes de morue en un seul endroit! Notre processus de longue matuaration dans le sel garantit la saveur unique, la texture douce et les tranches succulentes de notre poisson pr\u00e9f\u00e9r\u00e9, pr\u00eat \u00e0 cuisiner!","alternateName":"Riberalves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riberalves.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/riberalves.pt\/fr\/wp-json\/wp\/v2\/receitas\/8875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riberalves.pt\/fr\/wp-json\/wp\/v2\/receitas"}],"about":[{"href":"https:\/\/riberalves.pt\/fr\/wp-json\/wp\/v2\/types\/receitas"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riberalves.pt\/fr\/wp-json\/wp\/v2\/media\/7283"}],"wp:attachment":[{"href":"https:\/\/riberalves.pt\/fr\/wp-json\/wp\/v2\/media?parent=8875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riberalves.pt\/fr\/wp-json\/wp\/v2\/categories?post=8875"},{"taxonomy":"colecoes","embeddable":true,"href":"https:\/\/riberalves.pt\/fr\/wp-json\/wp\/v2\/colecoes?post=8875"},{"taxonomy":"tipos-bacalhau","embeddable":true,"href":"https:\/\/riberalves.pt\/fr\/wp-json\/wp\/v2\/tipos-bacalhau?post=8875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}