{"id":2572,"date":"2019-12-14T15:55:37","date_gmt":"2019-12-14T15:55:37","guid":{"rendered":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/"},"modified":"2021-06-24T14:53:55","modified_gmt":"2021-06-24T13:53:55","slug":"riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente","status":"publish","type":"noticias","link":"https:\/\/riberalves.pt\/pt-br\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/","title":{"rendered":"Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente"},"content":{"rendered":"<p>O s\u00edmbolo maior da Gastronomia portuguesa \u2013 o bacalhau \u2013 est\u00e1 em destaque em mais uma edi\u00e7\u00e3o do Festival da Comida Continente, j\u00e1 no pr\u00f3ximo fim-de-semana, no Porto. A Riberalves, marca refer\u00eancia de bacalhau em Portugal, estreita a parceria com o Continente e apresenta-se no Parque da Cidade colocando o bacalhau no centro das aten\u00e7\u00f5es, destacando-o pela sua qualidade, versatilidade e, acima de tudo, pelo seu valor saud\u00e1vel.<\/p>\n<p>Peixe de origem 100% selvagem, rico em prote\u00edna e pobre em gordura, o bacalhau \u00e9 o aliado perfeito de uma alimenta\u00e7\u00e3o equilibrada, valorizando as mais diversas receitas, sejam elas as mais tradicionais, ou as interpretadas pela nova cozinha. Ser\u00e1 precisamente o chef Estrela Michelin Miguel Laffan, embaixador da Riberalves, a apresentar um Workshop, no domingo, com as suas saud\u00e1veis dicas de Ver\u00e3o, em torno do bacalhau. Ao mesmo tempo, a Riberalves vai ao encontro dos consumidores no Espa\u00e7o Bio e Saud\u00e1vel do Festival da Comida Continente, destacando as caracter\u00edsticas que fazem do bacalhau uma das melhores prote\u00ednas animais dispon\u00edveis na nossa alimenta\u00e7\u00e3o.<\/p>\n<p>\u201cO Festival da Comida Continente tornou-se um extraordin\u00e1rio evento, de celebra\u00e7\u00e3o da gastronomia e de proximidade com os consumidores. A Riberalves marca naturalmente presen\u00e7a, enquanto marca de refer\u00eancia de bacalhau, valorizando este patrim\u00f3nio que \u00e9 o bacalhau, um peixe \u00fanico, na sua qualidade, sabor e valor saud\u00e1vel\u201d, afirma Marilina Louro, respons\u00e1vel de Marketing da Riberalves.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O s\u00edmbolo maior da Gastronomia portuguesa \u2013 o bacalhau \u2013 est\u00e1 em destaque em mais uma edi\u00e7\u00e3o do Festival da Comida Continente, j\u00e1 no pr\u00f3ximo fim-de-semana, no Porto. A Riberalves, marca refer\u00eancia de bacalhau em Portugal, estreita a parceria com o Continente e apresenta-se no Parque da Cidade colocando o bacalhau no centro das aten\u00e7\u00f5es, [&hellip;]<\/p>\n","protected":false},"featured_media":2573,"template":"","class_list":["post-2572","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente - Riberalves<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente - Riberalves\" \/>\n<meta property=\"og:description\" content=\"O s\u00edmbolo maior da Gastronomia portuguesa \u2013 o bacalhau \u2013 est\u00e1 em destaque em mais uma edi\u00e7\u00e3o do Festival da Comida Continente, j\u00e1 no pr\u00f3ximo fim-de-semana, no Porto. A Riberalves, marca refer\u00eancia de bacalhau em Portugal, estreita a parceria com o Continente e apresenta-se no Parque da Cidade colocando o bacalhau no centro das aten\u00e7\u00f5es, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/\" \/>\n<meta property=\"og:site_name\" content=\"Riberalves\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-24T13:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/riberalves.pt\/wp-content\/uploads\/2020\/10\/foto-noticia-continente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1077\" \/>\n\t<meta property=\"og:image:height\" content=\"1077\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\\\/\",\"url\":\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\\\/\",\"name\":\"Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente - Riberalves\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/riberalves.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/riberalves.pt\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/foto-noticia-continente.jpg\",\"datePublished\":\"2019-12-14T15:55:37+00:00\",\"dateModified\":\"2021-06-24T13:53:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/riberalves.pt\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/foto-noticia-continente.jpg\",\"contentUrl\":\"https:\\\/\\\/riberalves.pt\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/foto-noticia-continente.jpg\",\"width\":1077,\"height\":1077},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/riberalves.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/riberalves.pt\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/riberalves.pt\\\/#website\",\"url\":\"https:\\\/\\\/riberalves.pt\\\/\",\"name\":\"Riberalves\",\"description\":\"O site com as melhores e mais criativas receitas de bacalhau em um \u00fanico lugar!\",\"alternateName\":\"Riberalves\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/riberalves.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente - Riberalves","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/","og_locale":"pt_BR","og_type":"article","og_title":"Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente - Riberalves","og_description":"O s\u00edmbolo maior da Gastronomia portuguesa \u2013 o bacalhau \u2013 est\u00e1 em destaque em mais uma edi\u00e7\u00e3o do Festival da Comida Continente, j\u00e1 no pr\u00f3ximo fim-de-semana, no Porto. A Riberalves, marca refer\u00eancia de bacalhau em Portugal, estreita a parceria com o Continente e apresenta-se no Parque da Cidade colocando o bacalhau no centro das aten\u00e7\u00f5es, [&hellip;]","og_url":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/","og_site_name":"Riberalves","article_modified_time":"2021-06-24T13:53:55+00:00","og_image":[{"width":1077,"height":1077,"url":"https:\/\/riberalves.pt\/wp-content\/uploads\/2020\/10\/foto-noticia-continente.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/","url":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/","name":"Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente - Riberalves","isPartOf":{"@id":"https:\/\/riberalves.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/#primaryimage"},"image":{"@id":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/#primaryimage"},"thumbnailUrl":"https:\/\/riberalves.pt\/wp-content\/uploads\/2020\/10\/foto-noticia-continente.jpg","datePublished":"2019-12-14T15:55:37+00:00","dateModified":"2021-06-24T13:53:55+00:00","breadcrumb":{"@id":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/#primaryimage","url":"https:\/\/riberalves.pt\/wp-content\/uploads\/2020\/10\/foto-noticia-continente.jpg","contentUrl":"https:\/\/riberalves.pt\/wp-content\/uploads\/2020\/10\/foto-noticia-continente.jpg","width":1077,"height":1077},{"@type":"BreadcrumbList","@id":"https:\/\/riberalves.pt\/noticias\/riberalves-destaca-o-valor-saudavel-do-bacalhau-no-festival-da-comida-continente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/riberalves.pt\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/riberalves.pt\/noticias\/"},{"@type":"ListItem","position":3,"name":"Riberalves destaca o valor saud\u00e1vel do bacalhau no festival da comida continente"}]},{"@type":"WebSite","@id":"https:\/\/riberalves.pt\/#website","url":"https:\/\/riberalves.pt\/","name":"Riberalves","description":"O site com as melhores e mais criativas receitas de bacalhau em um \u00fanico lugar!","alternateName":"Riberalves","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riberalves.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/riberalves.pt\/pt-br\/wp-json\/wp\/v2\/noticias\/2572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riberalves.pt\/pt-br\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/riberalves.pt\/pt-br\/wp-json\/wp\/v2\/types\/noticias"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riberalves.pt\/pt-br\/wp-json\/wp\/v2\/media\/2573"}],"wp:attachment":[{"href":"https:\/\/riberalves.pt\/pt-br\/wp-json\/wp\/v2\/media?parent=2572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}